{"id":1875,"date":"2021-05-18T08:23:22","date_gmt":"2021-05-18T08:23:22","guid":{"rendered":"https:\/\/www.iriz-consulting.com\/?p=1875"},"modified":"2024-04-08T09:50:15","modified_gmt":"2024-04-08T09:50:15","slug":"reussissez-votre-certification-pega","status":"publish","type":"post","link":"https:\/\/www.iriz-consulting.com\/en\/2021\/05\/18\/reussissez-votre-certification-pega\/","title":{"rendered":"R\u00e9ussissez votre certification Pega !"},"content":{"rendered":"<p>En tant que formatrice Pega, j\u2019ai form\u00e9 de nombreuses personnes aux cursus de la Pega Academy. Si vous \u00a0d\u00e9butez sur Pega et vous vous demandez comment faire pour obtenir votre certification rapidement, voici quelques conseils pour vous aider \u00e0 atteindre votre objectif.<\/p>\n\n\n\n<p>Dans cet article, nous allons voir les deux options de formations qui s\u2019offrent \u00e0 vous&nbsp;:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>en auto-formation sur le site de la Pega Academy &nbsp;<\/li>\n\n\n\n<li>avec un formateur autoris\u00e9 par Pega<\/li>\n<\/ul>\n\n\n\n<p><\/p>\n\n\n\n<h5 class=\"wp-block-heading\">L\u2019auto-formation<\/h5>\n\n\n\n<p>En fonction de votre exp\u00e9rience, il vous faudra pr\u00e9voir entre 2 et 4 semaines \u00e0 temps plein pour compl\u00e9ter les formations System Architect et Business Architect (lecture du cours et r\u00e9alisation des exercices). Il faut savoir que tous les cours dispens\u00e9s par la Pega Academy sont en anglais. Ponctuellement, certains cours sont traduits en fran\u00e7ais, mais ce n\u2019est pas syst\u00e9matique. Lorsque vous lisez le cours, il est conseill\u00e9 d\u2019avoir la Plateforme Pega ouverte dans un autre onglet de votre navigateur, pour pouvoir visualiser clairement comment configurer les points mentionn\u00e9s dans le cours.<\/p>\n\n\n\n<p>En effet, cette technique est particuli\u00e8rement appropri\u00e9e pour les personnes qui ont une m\u00e9moire visuelle. \u00c0 la fin de chaque module de cours, vous acc\u00e9dez \u00e0 des QCM pour v\u00e9rifier progressivement votre assimilation des connaissances. Puis, vous trouverez des challenges, qui sont des exercices pratiques de programmation avec Pega. Il est recommand\u00e9 de tous les faire. \u00c0 la fin de tous les modules de cours et des challenges, il y a un test de fin de mission. Ce test, sous forme de QCM, reprend l\u2019ensemble des notions vues dans le cours. Il vous faudra environ 1h30 pour le terminer. Si vous avez plus de 80% de bonnes r\u00e9ponses \u00e0 ce test, alors Pega consid\u00e8re que vous \u00eates pr\u00eat pour passer la certification.<\/p>\n\n\n\n<p>M\u00eame en ayant lu le cours de la Pega Academy consciencieusement, il est possible que certains concepts ne soient pas clairs pour vous. C\u2019est la raison pour laquelle il est recommand\u00e9 de trouver un coll\u00e8gue ou une autre personne exp\u00e9riment\u00e9e en Pega, que vous pouvez contacter quand vous avez des questions \u00e0 poser. Sans aide ext\u00e9rieure, une seconde lecture du cours est quasiment syst\u00e9matiquement n\u00e9cessaire.<\/p>\n\n\n\n<p>Les cours Pega Academy sont accessibles librement sans aucun frais. Il vous suffit simplement de vous cr\u00e9er un compte sur sur <a href=\"https:\/\/academy.pega.com\/\">https:\/\/academy.pega.com\/<\/a> et de vous lancer sur la mission de votre choix\u00a0!<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Se former avec un.e formateur\/trice<\/h5>\n\n\n\n<p>Suivre une formation avec un.e formateur.trice Pega vous donne la possibilit\u00e9 d\u2019aborder plus facilement tous les concepts Pega et d\u2019avoir la r\u00e9ponse \u00e0 vos questions imm\u00e9diatement. De plus, la formation est dispens\u00e9e en fran\u00e7ais. Il y a donc une vraie valeur ajout\u00e9e \u00e0 suivre la formation avec un.e formateur.trice\u00a0: c\u2019est plus rapide, c\u2019est interactif\u00a0et c\u2019est en fran\u00e7ais !<\/p>\n\n\n\n<p>Par ailleurs, la certification Pega Certified System Architect ou Pega Certified Business Architect est un passage obligatoire pour les consultants Pega et est tr\u00e8s souvent demand\u00e9e pour int\u00e9grer un projet. Un.e formateur.trice saura donc vous guider au mieux sur les choses importantes \u00e0 retenir et le type de questions que vous pourriez avoir durant l\u2019examen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Certification System Architect<\/h5>\n\n\n\n<p>Pour r\u00e9ussir la certification Pega Certified System Architect, il faut avoir un score minimum de 65% de bonnes r\u00e9ponses. Il y a 60 questions au total, sous forme de QCM. Quatre de ces questions sont des \u00ab\u00a0fausses\u00a0\u00bb questions, c\u2019est-\u00e0-dire, des questions qui ne sont pas not\u00e9es, qui utilisent le vocabulaire de Pega mais qui n\u2019ont pas de sens et qui sont l\u00e0 uniquement pour d\u00e9tecter les \u00e9ventuels tricheurs. Il est en effet tr\u00e8s peu probable que deux personnes aient exactement les m\u00eames r\u00e9ponses \u00e0 ces quatre questions. Du coup, lorsque vous voyez une question \u00e9trange r\u00e9pondez rapidement et ne perdez pas de temps dessus. Vous \u00eates not\u00e9 uniquement sur 56 questions. Vous aurez 2 heures pour r\u00e9pondre \u00e0 ces 60 questions si vous passez la certification en anglais\u00a0: vous avez 30 minutes de temps suppl\u00e9mentaire d\u2019examen car vous ne vivez pas dans un pays anglophone. Si vous choisissez de passer la certification en fran\u00e7ais vous n\u2019aurez qu\u20191h30 de temps d\u2019examen (la dur\u00e9e normale d\u2019examen).<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Certification Business Architect<\/h5>\n\n\n\n<p>Pour r\u00e9ussir la certification Pega Certified Business Architect, il faut avoir un score minimum de 70% de bonnes r\u00e9ponses. Il y a 50 questions au total sous forme de QCM. De la m\u00eame mani\u00e8re que pour la certification Pega Certified System Architect, quatre de ces questions sont des \u00ab\u00a0fausses\u00a0\u00bb questions. Vous aurez aussi 2 heures pour r\u00e9pondre \u00e0 ces 50 questions si vous passez la certification en anglais\u00a0(1h30 + 30 minutes de temps suppl\u00e9mentaire pour les r\u00e9sidents de pays non-anglophones). S\u2019il y a une certification en fran\u00e7ais de disponible vous n\u2019aurez qu\u20191h30 de temps d\u2019examen.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Les types de questions d&rsquo;examen<\/h5>\n\n\n\n<p>Les questions pr\u00e9sentes lors de l\u2019examen peuvent \u00eatre des questions courtes (un \u00e9nonc\u00e9 d\u2019une ligne ou deux) ou des questions longues (une mise en situation d\u2019un ou deux paragraphes). Il peut y avoir une ou plusieurs bonnes r\u00e9ponses \u00e0 cocher (le nombre de r\u00e9ponses \u00e0 cocher sera indiqu\u00e9) ou \u00e0 glisser-d\u00e9poser au bon endroit. Vous aurez un tableau Veleda \u00e0 disposition dans le centre d\u2019examen pour que vous puissiez prendre des notes, faire des calculs. Dans le cas o\u00f9 vous passez l\u2019examen chez vous (surveill\u00e9 par webcam), le logiciel vous permettant de passer l\u2019examen dispose d\u2019un onglet servant de feuille de brouillon virtuelle. Ce logiciel bloque \u00e9galement l\u2019utilisation de toutes les autres applications de votre ordinateur, vous emp\u00eachant ainsi d\u2019ouvrir Google. Le passage d\u2019une certification Pega co\u00fbte 175 dollars, que ce soit sur place ou \u00e0 distance.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Pas d\u2019\u00e9chec mais un gain d\u2019exp\u00e9rience<\/h5>\n\n\n\n<p>Si vous \u00e9chouez \u00e0 la certification, vous serez autoris\u00e9 \u00e0 la repasser \u00e0 nouveau au minimum 3 jours apr\u00e8s votre premi\u00e8re tentative. Si vous \u00e9chouez \u00e9galement \u00e0 la deuxi\u00e8me tentative, vous devrez attendre minimum 14 jours pour pouvoir la repasser une troisi\u00e8me fois. Vous ne pouvez pas passer plus de 3 fois la m\u00eame version de la certification. Attention, apr\u00e8s 3 \u00e9checs, vous devrez attendre la sortie de la nouvelle version de la certification.<\/p>\n\n\n\n<p>Si vous \u00e9chouez de peu \u00e0 la certification, il est recommand\u00e9 de la repasser au plus vite (la semaine suivante). En effet, le jour de l\u2019examen, vous aurez les r\u00e9sultats d\u00e9taill\u00e9s de votre score par th\u00e9matique. Vous saurez ainsi quels sont les th\u00e8mes \u00e0 retravailler et vous pourrez sp\u00e9cifiquement vous concentrer sur ceux-l\u00e0 lors de vos r\u00e9visions pour votre prochain passage. Si vous attendez trop longtemps, vous prenez le risque d\u2019oublier ce que vous aviez bien assimil\u00e9 lors de votre premier passage de la certification.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Pourquoi vous former chez IRIZ Consulting&nbsp;?<\/h5>\n\n\n\n<p>IRIZ Consulting offre des cursus de formations avec un.e formateur.trice, prenant en compte la pr\u00e9paration et le passage de la certification. Par exemple, pour le passage de la certification Pega Certified System Architect, nous proposons l\u2019option pr\u00e9paration et passage de la certification sous 3 semaines\u00a0:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Semaine 1\u00a0: 5 jours de cours\/exercices avec un.e formateur.trice.<\/li>\n\n\n\n<li>Semaine 2\u00a0: 3 jours de cours\/exercices + 2 jours de pr\u00e9paration \u00e0 la certification avec un.e formateur.trice.<\/li>\n\n\n\n<li>Semaine 3\u00a0:\u00a0 1 jour de pr\u00e9paration \u00e0 la certification avec un(e) formateur\/trice + r\u00e9vision en autonomie (le\/la formateur\/trice est disponible par email et t\u00e9l\u00e9phone si besoin) + passage de la certification.<\/li>\n<\/ul>\n\n\n\n<p>Vous pouvez consulter notre catalogue de formations via le lien suivant\u00a0:<br><a href=\"https:\/\/www.iriz-consulting.com\/en\/formations-pega\/\">https:\/\/www.iriz-consulting.com\/formations-pega\/<\/a> Vous souhaitez vous inscrire\u00a0? Vous souhaitez en discuter avec nous\u00a0?<\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/www.iriz-consulting.com\/en\/#footer-contact\"><strong>Get in touch with us<\/strong><\/a><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized is-style-default\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-1024x1024.png\" alt=\"formatrice pega\" class=\"wp-image-5706\" style=\"aspect-ratio:1;object-fit:cover;width:173px\" srcset=\"https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-1024x1024.png 1024w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-150x150.png 150w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-300x300.png 300w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-768x768.png 768w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-830x830.png 830w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-230x230.png 230w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-350x350.png 350w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega-480x480.png 480w, https:\/\/www.iriz-consulting.com\/wp-content\/uploads\/2021\/05\/formatrice-pega.png 1080w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><strong>Isabelle PERARNAUD,<\/strong> Formatrice officielle Pega chez IRIZ Consulting depuis 2019.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><\/p>","protected":false},"excerpt":{"rendered":"<p>En tant que formatrice Pega, j\u2019ai form\u00e9 de nombreuses personnes aux cursus de la Pega Academy. Si vous \u00a0d\u00e9butez sur Pega et vous vous demandez comment faire pour obtenir votre certification rapidement, voici quelques conseils pour vous aider \u00e0 atteindre votre objectif. Dans cet article, nous allons voir les deux options de formations qui s\u2019offrent [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":1852,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"none","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-1875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"_links":{"self":[{"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/posts\/1875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/comments?post=1875"}],"version-history":[{"count":14,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/posts\/1875\/revisions"}],"predecessor-version":[{"id":6565,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/posts\/1875\/revisions\/6565"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/media\/1852"}],"wp:attachment":[{"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/media?parent=1875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/categories?post=1875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iriz-consulting.com\/en\/wp-json\/wp\/v2\/tags?post=1875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}